{"id":76462,"date":"2026-08-28T11:41:01","date_gmt":"2026-08-28T09:41:01","guid":{"rendered":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03.png"},"modified":"2026-08-28T11:41:01","modified_gmt":"2026-08-28T09:41:01","slug":"img_6a9157ad94e03","status":"inherit","type":"attachment","link":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/fotos-culinesse-2026-een-festival-dat-gezinnen-jongeren-en-oudere-jongeren-blijft-boeien\/img_6a9157ad94e03\/","title":{"rendered":"img_6a9157ad94e03"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"tdm_status":"","tdm_grid_status":""},"class_list":["post-76462","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03.png'><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"500\" src=\"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-368x500.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-368x500.png 368w, https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-309x420.png 309w, https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-300x407.png 300w, https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03.png 436w\" sizes=\"auto, (max-width: 368px) 100vw, 368px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":436,"height":592,"file":"2026\/08\/img_6a9157ad94e03.png","filesize":389730,"sizes":{"medium":{"file":"img_6a9157ad94e03-368x500.png","width":368,"height":500,"filesize":258537,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-368x500.png"},"thumbnail":{"file":"img_6a9157ad94e03-200x200.png","width":200,"height":200,"filesize":71027,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-200x200.png"},"td_0x420":{"file":"img_6a9157ad94e03-309x420.png","width":309,"height":420,"filesize":188953,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-309x420.png"},"td_80x60":{"file":"img_6a9157ad94e03-80x60.png","width":80,"height":60,"filesize":8458,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-80x60.png"},"td_218x150":{"file":"img_6a9157ad94e03-218x150.png","width":218,"height":150,"filesize":45745,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-218x150.png"},"td_300x0":{"file":"img_6a9157ad94e03-300x407.png","width":300,"height":407,"filesize":178714,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-300x407.png"},"td_324x400":{"file":"img_6a9157ad94e03-324x400.png","width":324,"height":400,"filesize":192519,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-324x400.png"},"td_485x360":{"file":"img_6a9157ad94e03-436x360.png","width":436,"height":360,"filesize":215104,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-436x360.png"},"td_265x198":{"file":"img_6a9157ad94e03-265x198.png","width":265,"height":198,"filesize":73892,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-265x198.png"},"td_741x486":{"file":"img_6a9157ad94e03-436x486.png","width":436,"height":486,"filesize":308782,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03-436x486.png"},"full":{"file":"img_6a9157ad94e03.png","width":436,"height":592,"mime_type":"image\/png","source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"alt":""}},"post":76445,"source_url":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-content\/uploads\/2026\/08\/img_6a9157ad94e03.png","filename":"img_6a9157ad94e03.png","filesize":389730,"_links":{"self":[{"href":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-json\/wp\/v2\/media\/76462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-json\/wp\/v2\/comments?post=76462"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":76445,"href":"https:\/\/www.rotterdam-nesselande.nl\/nieuws\/zuidplas\/rotterdam\/nesselande\/wonen\/wp-json\/wp\/v2\/posts\/76445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}